{"id":91429,"date":"2022-10-03T11:00:03","date_gmt":"2022-10-03T15:00:03","guid":{"rendered":"https:\/\/seyo.cl\/index.php\/producto\/polera-de-mujer-manga-larga-superheroe-buttman-batman\/"},"modified":"2022-10-03T11:04:18","modified_gmt":"2022-10-03T15:04:18","slug":"polera-de-mujer-manga-larga-superheroe-buttman-batman","status":"publish","type":"product","link":"https:\/\/seyo.cl\/index.php\/producto\/polera-de-mujer-manga-larga-superheroe-buttman-batman\/","title":{"rendered":"Polera De Mujer Manga Larga SUPERHEROE BUTTMAN, BATMAN"},"content":{"rendered":"<p>ESTAMPADOS SEYO<br \/>\nTENEMOS TALLAS DESDE LAS CHICAS A LAS EXTRA GRANDES.<br \/>\nPoleras y Polerones 100% algod\u00f3n<br \/>\nProductos de Alta Calidad<br \/>\nRevise nuestra variedad de Dise\u00f1os, Colores y Tallas.<br \/>\nLos env\u00edos se realizan lo m\u00e1s pronto posible, para que reciba los productos en la puerta de su casa sin demora.<br \/>\nEl estampado se realiza al momento de hacer la compra y se env\u00eda al d\u00eda siguiente.<br \/>\nPor esto podemos hacer variaciones de dise\u00f1o, personalizaciones, aplicaci\u00f3n de nombres, entre otros, lo que desee, y se ajuste dentro de las posibilidades. Con un peque\u00f1o costo adicional dependiendo de lo que solicite.<br \/>\nRealiza con confianza todas las consultas te responderemos con la mejor disposici\u00f3n.<\/p>\n<p>(Si su compra es a trav\u00e9s de MercadoLibre recuerde que los env\u00edos son gratuitos cuando las compras son mayores a 16990, y que los env\u00edos los hacemos a trav\u00e9s de mercado env\u00edos para que MercadoLibre asegure el 100% de su dinero)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De calce cl\u00e1sico con silueta muy c\u00f3modo, 100% algod\u00f3n. Estampado con vinil textil de la m\u00e1s alta calidad.<\/p>\n","protected":false},"featured_media":91430,"template":"","meta":[],"product_cat":[164,176,178],"product_tag":[182,191,181],"_links":{"self":[{"href":"https:\/\/seyo.cl\/index.php\/wp-json\/wp\/v2\/product\/91429"}],"collection":[{"href":"https:\/\/seyo.cl\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/seyo.cl\/index.php\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/seyo.cl\/index.php\/wp-json\/wp\/v2\/product\/91429\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/seyo.cl\/index.php\/wp-json\/wp\/v2\/media\/91430"}],"wp:attachment":[{"href":"https:\/\/seyo.cl\/index.php\/wp-json\/wp\/v2\/media?parent=91429"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/seyo.cl\/index.php\/wp-json\/wp\/v2\/product_cat?post=91429"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/seyo.cl\/index.php\/wp-json\/wp\/v2\/product_tag?post=91429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}